{"id":11949,"date":"2024-07-18T10:43:39","date_gmt":"2024-07-18T08:43:39","guid":{"rendered":"https:\/\/bohome.ma\/orbis_agri\/?page_id=11949"},"modified":"2024-07-31T16:10:42","modified_gmt":"2024-07-31T14:10:42","slug":"fruits-rouges","status":"publish","type":"page","link":"https:\/\/bohome.ma\/orbis_agri\/fruits-rouges\/","title":{"rendered":"Fruits rouges"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"11949\" class=\"elementor elementor-11949\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-45bd8e1 elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"45bd8e1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6a36041\" data-id=\"6a36041\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f04a71b elementor-widget elementor-widget-agraria_core_separator\" data-id=\"f04a71b\" data-element_type=\"widget\" data-widget_type=\"agraria_core_separator.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-separator clear qodef-position--center \">\n\t<div class=\"qodef-m-line\" style=\"border-color: #02010100\"><\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-552a359\" data-id=\"552a359\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a0e907 elementor-widget elementor-widget-agraria_core_section_title\" data-id=\"9a0e907\" data-element_type=\"widget\" data-widget_type=\"agraria_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left qodef-title-break--disabled\">\n\t\t\t\t<h2 class=\"qodef-m-title\" >\n\t\t\t\t\tFruits rouges<br \/> Orbis Berries\t\t\t<\/h2>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-93b58eb elementor-widget elementor-widget-text-editor\" data-id=\"93b58eb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<div><span lang=\"FR\">Dot\u00e9e d\u2019une superficie globale de 905 hectares, dont plus de 57 hectares sont d\u00e9di\u00e9s \u00e0 la plantation, la ferme de Sidi Yahya du Gharb, \u00e9galement connue sous le nom d&rsquo;Orbis Berries, est une exploitation agricole sp\u00e9cialis\u00e9e dans la culture des fruits rouges. <\/span><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c72b7f elementor-widget elementor-widget-text-editor\" data-id=\"2c72b7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div><div><span lang=\"FR\">Ces cultures incluent\u00a0<\/span><span lang=\"FR\">les myrtilles et les baies de goji, qui sont reconnues pour leur haute valeur nutritionnelle et leur popularit\u00e9 croissante sur les march\u00e9s locaux et internationaux.<\/span><\/div><\/div><div><p><span lang=\"FR\">La ferme Orbis Berries se distingue par son adoption de technologies agricoles avanc\u00e9es, qui incluent une gestion intelligente de l\u2019irrigation et de la fertigation. Ces technologies permettent d&rsquo;optimiser l&rsquo;utilisation des ressources en eau et en nutriments, en assurant que les plantes re\u00e7oivent pr\u00e9cis\u00e9ment ce dont elles ont besoin, quand elles en ont besoin. Le syst\u00e8me d&rsquo;irrigation est automatis\u00e9 et contr\u00f4l\u00e9 par des capteurs qui surveillent en temps r\u00e9el l&rsquo;humidit\u00e9 du sol et les besoins en eau des plantes. La fertigation, quant \u00e0 elle, int\u00e8gre l&rsquo;apport de nutriments avec l&rsquo;irrigation, maximisant ainsi l&rsquo;efficacit\u00e9 de l&rsquo;utilisation des engrais.<\/span><\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76ca766 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"76ca766\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f061751\" data-id=\"f061751\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bec4f3 elementor-widget elementor-widget-agraria_core_text_marquee\" data-id=\"1bec4f3\" data-element_type=\"widget\" data-widget_type=\"agraria_core_text_marquee.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-text-marquee qodef-text-marquee-286 qodef-layout--default qodef-direction--left\" >\n\t<div class=\"qodef-m-content\" >\n\t\t<div class=\"qodef-m-content-inner\">\n\t\t\t\t\t\t\t<span class=\"qodef-m-text-1\" style=\"color:#EEE6D3\">\n\t\t\t\t\t\t\t\t\t\tFRUITS ROUGES\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"qodef-m-text-2\" style=\"color:#EEE6D3\">\n\t\t\t\t\t\t\t\t\t\tFRUITS ROUGES\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e58da09 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"e58da09\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1cae0c1\" data-id=\"1cae0c1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12d0a5d elementor-widget elementor-widget-agraria_core_banner\" data-id=\"12d0a5d\" data-element_type=\"widget\" data-widget_type=\"agraria_core_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-banner qodef-layout--link-overlay \">\n\t<div class=\"qodef-m-image\" >\n\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1203\" height=\"938\" src=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-fruits-rouges-cultures.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-fruits-rouges-cultures.jpg 1203w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-fruits-rouges-cultures-300x234.jpg 300w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-fruits-rouges-cultures-1024x798.jpg 1024w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-fruits-rouges-cultures-768x599.jpg 768w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-fruits-rouges-cultures-600x468.jpg 600w\" sizes=\"(max-width: 1203px) 100vw, 1203px\" \/><\/div>\n\t<div class=\"qodef-m-content\">\n\t\t<div class=\"qodef-m-content-inner\" >\n\t\t\t\t\t\t\t<h3 class=\"qodef-m-title\" style=\"color: #FFFFFF\">\n\t\tBAIE DE GOJI\t<\/h3>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a itemprop=\"url\" href=\"#\" class=\"qodef-m-banner-link\" target=\"_self\"><\/a>\n\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-679510d\" data-id=\"679510d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b6a3498 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b6a3498\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-a11de4f\" data-id=\"a11de4f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1393e91 elementor-widget elementor-widget-agraria_core_banner\" data-id=\"1393e91\" data-element_type=\"widget\" data-widget_type=\"agraria_core_banner.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-banner qodef-layout--link-overlay \">\n\t<div class=\"qodef-m-image\" >\n\t<img decoding=\"async\" width=\"1203\" height=\"938\" src=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-fruits-rouges-cultures-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-fruits-rouges-cultures-2.jpg 1203w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-fruits-rouges-cultures-2-300x234.jpg 300w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-fruits-rouges-cultures-2-1024x798.jpg 1024w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-fruits-rouges-cultures-2-768x599.jpg 768w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-fruits-rouges-cultures-2-600x468.jpg 600w\" sizes=\"(max-width: 1203px) 100vw, 1203px\" \/><\/div>\n\t<div class=\"qodef-m-content\">\n\t\t<div class=\"qodef-m-content-inner\" >\n\t\t\t\t\t\t\t<h3 class=\"qodef-m-title\" style=\"color: #FFFFFF\">\n\t\tMYRTILLES\t<\/h3>\n\t\t\t\t\t<\/div>\n\t<\/div>\n\t<a itemprop=\"url\" href=\"#\" class=\"qodef-m-banner-link\" target=\"_self\"><\/a>\n\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-89590e6 elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"89590e6\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-c424c77\" data-id=\"c424c77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-97cf611 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"97cf611\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-qi-section-title  qodef-decoration--italic  qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\tDomaine\t<\/h4>\n\t\t\t<div class=\"qodef-m-text\"><div><span>Sidi Yahya du Gharb<\/span><\/div><div><span>(ORBIS Berries)<\/span><\/div><\/div>\n\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-4b4ebf1\" data-id=\"4b4ebf1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-427fec5 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"427fec5\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-qi-section-title  qodef-decoration--italic  qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\tVari\u00e9t\u00e9s\t<\/h4>\n\t\t\t<div class=\"qodef-m-text\"><p>Baie de Goji et Myrtilles<\/p><\/div>\n\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-e946045\" data-id=\"e946045\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3c66004 elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"3c66004\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-qi-section-title  qodef-decoration--italic  qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\tSuperficie (Ha)\t<\/h4>\n\t\t\t<div class=\"qodef-m-text\"><div><span>905 Ha<\/span><\/div><div><span>dont 57 Ha plant\u00e9e<\/span><\/div><\/div>\n\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-fb34680\" data-id=\"fb34680\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-96b5a2b elementor-widget elementor-widget-qi_addons_for_elementor_section_title\" data-id=\"96b5a2b\" data-element_type=\"widget\" data-widget_type=\"qi_addons_for_elementor_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-qi-section-title  qodef-decoration--italic  qodef-link--underline-draw qodef-subtitle-icon--left\">\n\t\t\t\t\t\t<h4 class=\"qodef-m-title\">\n\t\tBassins\t<\/h4>\n\t\t\t<div class=\"qodef-m-text\"><div><span>Une capacit\u00e9 totale de 33\u00a0000 m3<\/span><\/div><\/div>\n\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-df2145e elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"df2145e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2e40d9e\" data-id=\"2e40d9e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c5659a elementor-widget elementor-widget-agraria_core_section_title\" data-id=\"7c5659a\" data-element_type=\"widget\" data-widget_type=\"agraria_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left qodef-title-break--disabled\">\n\t\t\t\t<h2 class=\"qodef-m-title\" >\n\t\t\t\t\torbis berries\t\t\t<\/h2>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6390e7f elementor-widget elementor-widget-text-editor\" data-id=\"6390e7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div><p><span lang=\"FR\">En outre, la ferme utilise des pratiques de lutte int\u00e9gr\u00e9e pour la gestion des ravageurs et des maladies. Cette approche vise \u00e0 minimiser l&rsquo;utilisation de produits chimiques en favorisant des m\u00e9thodes de contr\u00f4le biologiques et m\u00e9caniques. Par exemple, la lutte int\u00e9gr\u00e9e peut inclure l&rsquo;utilisation de pr\u00e9dateurs naturels pour contr\u00f4ler les populations de ravageurs ou l&rsquo;application de biopesticides qui sont moins nocifs pour l&rsquo;environnement et la sant\u00e9 humaine.<\/span><\/p><\/div><div><p><span lang=\"FR\">Le projet de la ferme Orbis Berries est r\u00e9alis\u00e9 en partenariat avec l\u2019Arab Authority for Agricultural Investment and Development (AAAID), une organisation qui soutient le d\u00e9veloppement agricole durable dans la r\u00e9gion arabe. Ce partenariat apporte non seulement un soutien financier mais aussi un savoir-faire technique et une expertise en gestion agricole, contribuant \u00e0 la r\u00e9ussite et \u00e0 la durabilit\u00e9 du projet.<\/span><\/p><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-98ceed9 elementor-widget elementor-widget-text-editor\" data-id=\"98ceed9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p><span lang=\"FR\">Gr\u00e2ce \u00e0 ces innovations et \u00e0 ce partenariat strat\u00e9gique, la ferme de Sidi Yahya du Gharb se positionne comme un mod\u00e8le de l&rsquo;agriculture moderne et durable, capable de r\u00e9pondre aux d\u00e9fis actuels de la production agricole tout en respectant l&rsquo;environnement.<\/span><\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5d7e7a6\" data-id=\"5d7e7a6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-89cf606 elementor-widget elementor-widget-image\" data-id=\"89cf606\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"618\" height=\"788\" src=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-carte-Orbis-Berries.png\" class=\"attachment-large size-large wp-image-12292\" alt=\"\" srcset=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-carte-Orbis-Berries.png 618w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-carte-Orbis-Berries-235x300.png 235w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-carte-Orbis-Berries-9x12.png 9w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-carte-Orbis-Berries-600x765.png 600w\" sizes=\"(max-width: 618px) 100vw, 618px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b007a59 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"b007a59\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-52a7b58\" data-id=\"52a7b58\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-11e8dfe elementor-widget elementor-widget-agraria_core_image_gallery\" data-id=\"11e8dfe\" data-element_type=\"widget\" data-widget_type=\"agraria_core_image_gallery.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-image-gallery qodef-magnific-popup qodef-popup-gallery qodef-grid qodef-layout--columns  qodef-gutter--small qodef-vertical-gutter--small qodef-col-num--4  qodef-responsive--custom qodef-col-num--1440--4 qodef-col-num--1366--4 qodef-col-num--1024--3 qodef-col-num--768--2 qodef-col-num--680--1 qodef-col-num--480--1 qodef-swiper--show-pagination\">\n\t<div class=\"qodef-grid-inner\">\n\t\t<div class=\"qodef-e qodef-image-wrapper qodef-grid-item \">\n\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-3-1.jpg\" data-type=\"image\" title=\"\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"1027\" src=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-3-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-3-1.jpg 880w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-3-1-257x300.jpg 257w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-3-1-877x1024.jpg 877w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-3-1-768x896.jpg 768w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-3-1-600x700.jpg 600w\" sizes=\"(max-width: 880px) 100vw, 880px\" \/>\t\t\t<\/a>\n\t<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item \">\n\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-4-1.jpg\" data-type=\"image\" title=\"\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"1027\" src=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-4-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-4-1.jpg 880w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-4-1-257x300.jpg 257w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-4-1-877x1024.jpg 877w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-4-1-768x896.jpg 768w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-4-1-600x700.jpg 600w\" sizes=\"(max-width: 880px) 100vw, 880px\" \/>\t\t\t<\/a>\n\t<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item \">\n\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-2-1.jpg\" data-type=\"image\" title=\"\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"1027\" src=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-2-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-2-1.jpg 880w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-2-1-257x300.jpg 257w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-2-1-877x1024.jpg 877w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-2-1-768x896.jpg 768w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-2-1-600x700.jpg 600w\" sizes=\"(max-width: 880px) 100vw, 880px\" \/>\t\t\t<\/a>\n\t<\/div>\n<div class=\"qodef-e qodef-image-wrapper qodef-grid-item \">\n\t\t\t<a class=\"qodef-popup-item\" itemprop=\"image\" href=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-1.jpg\" data-type=\"image\" title=\"\">\n\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"880\" height=\"1027\" src=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-1.jpg 880w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-1-257x300.jpg 257w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-1-877x1024.jpg 877w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-1-768x896.jpg 768w, https:\/\/bohome.ma\/orbis_agri\/wp-content\/uploads\/2024\/07\/orbis-agro-industry-domaines-1-600x700.jpg 600w\" sizes=\"(max-width: 880px) 100vw, 880px\" \/>\t\t\t<\/a>\n\t<\/div>\n\t<\/div>\n<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6ad8e8a elementor-section-full_width qodef-elementor-content-grid elementor-section-height-default elementor-section-height-default\" data-id=\"6ad8e8a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-d6a6bf3\" data-id=\"d6a6bf3\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a43f46d elementor-widget elementor-widget-text-editor\" data-id=\"a43f46d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>ORBIS Agro Industry<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ef17c44 elementor-widget elementor-widget-agraria_core_section_title\" data-id=\"ef17c44\" data-element_type=\"widget\" data-widget_type=\"agraria_core_section_title.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"qodef-shortcode qodef-m  qodef-section-title qodef-alignment--left qodef-title-break--disabled\">\n\t\t\t\t<h2 class=\"qodef-m-title\" >\n\t\t\t\t\tORBIS Berries\t\t\t<\/h2>\n\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-0eccbb9\" data-id=\"0eccbb9\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5705c1d elementor-widget__width-initial elementor-widget elementor-widget-video\" data-id=\"5705c1d\" data-element_type=\"widget\" data-settings=\"{&quot;youtube_url&quot;:&quot;https:\\\/\\\/www.youtube.com\\\/watch?v=6CjUQt_yKJU&amp;pp=ygUNb3JiaXMgYmVycmllcw%3D%3D&quot;,&quot;video_type&quot;:&quot;youtube&quot;,&quot;controls&quot;:&quot;yes&quot;}\" data-widget_type=\"video.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.23.0 - 05-08-2024 *\/\n.elementor-widget-video .elementor-widget-container{overflow:hidden;transform:translateZ(0)}.elementor-widget-video .elementor-wrapper{aspect-ratio:var(--video-aspect-ratio)}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{height:100%;width:100%;display:flex;border:none;background-color:#000}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-wrapper{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-wrapper iframe,.elementor-widget-video .elementor-wrapper video{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .elementor-open-inline .elementor-custom-embed-image-overlay{position:absolute;top:0;right:0;bottom:0;left:0;background-size:cover;background-position:50%}.elementor-widget-video .elementor-custom-embed-image-overlay{cursor:pointer;text-align:center}.elementor-widget-video .elementor-custom-embed-image-overlay:hover .elementor-custom-embed-play i{opacity:1}.elementor-widget-video .elementor-custom-embed-image-overlay img{display:block;width:100%;aspect-ratio:var(--video-aspect-ratio);-o-object-fit:cover;object-fit:cover;-o-object-position:center center;object-position:center center}@supports not (aspect-ratio:1\/1){.elementor-widget-video .elementor-custom-embed-image-overlay{position:relative;overflow:hidden;height:0;padding-bottom:calc(100% \/ var(--video-aspect-ratio))}.elementor-widget-video .elementor-custom-embed-image-overlay img{position:absolute;top:0;right:0;bottom:0;left:0}}.elementor-widget-video .e-hosted-video .elementor-video{-o-object-fit:cover;object-fit:cover}.e-con-inner>.elementor-widget-video,.e-con>.elementor-widget-video{width:var(--container-widget-width);--flex-grow:var(--container-widget-flex-grow)}<\/style>\t\t<div class=\"elementor-wrapper elementor-open-inline\">\n\t\t\t<div class=\"elementor-video\"><\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Fruits rouges Orbis Berries Dot\u00e9e d\u2019une superficie globale de 905 hectares, dont plus de 57 hectares sont d\u00e9di\u00e9s \u00e0 la plantation, la ferme de Sidi Yahya du Gharb, \u00e9galement connue sous le nom d&rsquo;Orbis Berries, est une exploitation agricole sp\u00e9cialis\u00e9e dans la culture des fruits rouges. Ces cultures incluent\u00a0les myrtilles et les baies de goji, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-full-width.php","meta":{"om_disable_all_campaigns":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-11949","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/bohome.ma\/orbis_agri\/wp-json\/wp\/v2\/pages\/11949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bohome.ma\/orbis_agri\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/bohome.ma\/orbis_agri\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/bohome.ma\/orbis_agri\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bohome.ma\/orbis_agri\/wp-json\/wp\/v2\/comments?post=11949"}],"version-history":[{"count":19,"href":"https:\/\/bohome.ma\/orbis_agri\/wp-json\/wp\/v2\/pages\/11949\/revisions"}],"predecessor-version":[{"id":12344,"href":"https:\/\/bohome.ma\/orbis_agri\/wp-json\/wp\/v2\/pages\/11949\/revisions\/12344"}],"wp:attachment":[{"href":"https:\/\/bohome.ma\/orbis_agri\/wp-json\/wp\/v2\/media?parent=11949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}